{"id":145,"count":1,"description":"","link":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/","name":"Gateway","slug":"gateway","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gateway Archives - Ekspresa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gateway Archives - Ekspresa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/\" \/>\n<meta property=\"og:site_name\" content=\"Ekspresa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gateway Archives - Ekspresa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/","og_locale":"es_ES","og_type":"article","og_title":"Gateway Archives - Ekspresa","og_url":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/","og_site_name":"Ekspresa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/","url":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/","name":"Gateway Archives - Ekspresa","isPartOf":{"@id":"https:\/\/ekspresa.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/ekspresa.com\/es\/categoria-producto\/gateway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ekspresa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gateway"}]},{"@type":"WebSite","@id":"https:\/\/ekspresa.com\/es\/#website","url":"https:\/\/ekspresa.com\/es\/","name":"Ekspresa","description":"Engineering services","publisher":{"@id":"https:\/\/ekspresa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ekspresa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ekspresa.com\/es\/#organization","name":"Ekspresa","url":"https:\/\/ekspresa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ekspresa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ekspresa.com\/wp-content\/uploads\/2026\/03\/cropped-ICO.png","contentUrl":"https:\/\/ekspresa.com\/wp-content\/uploads\/2026\/03\/cropped-ICO.png","width":1007,"height":998,"caption":"Ekspresa"},"image":{"@id":"https:\/\/ekspresa.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ekspresa.com\/es\/wp-json\/wp\/v2\/product_cat\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekspresa.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ekspresa.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/ekspresa.com\/es\/wp-json\/wp\/v2\/product?product_cat=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}